{"id":18,"date":"2022-12-30T14:15:18","date_gmt":"2022-12-30T13:15:18","guid":{"rendered":"http:\/\/unser-quartier.de\/tmp-musterblog2\/?page_id=18"},"modified":"2023-12-21T16:06:05","modified_gmt":"2023-12-21T15:06:05","slug":"aktuell-termine","status":"publish","type":"post","link":"https:\/\/unser-quartier.de\/kali50plus\/aktuell-termine\/","title":{"rendered":"Aktuelle Termine"},"content":{"rendered":"<h3>Runde Tische<\/h3>\n<p>Das ist die Vorgehensweise: In den folgenden Stadtteilen <strong>Geisbruch<\/strong>, <strong>Gestfeld<\/strong> und <strong>Niersenbruch<\/strong> haben sich Runde Tische gebildet, die die Anregungen und Ideen aus den 50plus-Konferenzen umsetzen. Interessierte B\u00fcrgerinnen und B\u00fcrger sind weiterhin zur Mitarbeit eingeladen. Alle Runden Tische treffen sich regelm\u00e4\u00dfig, haben mit ersten Aktivit\u00e4ten begonnen und arbeiten st\u00e4ndig daran, Neues anzubieten.<\/p>\n<h3><a href=\"https:\/\/www.schulferien-online.de\/\" target=\"_blank\" rel=\"noopener noreferrer follow external\" data-wpel-link=\"external\" class=\"ext-link wpel-icon-right\">Schulferien Online<span class=\"wpel-icon wpel-image wpel-icon-8\"><\/span><\/a><\/h3>\n<h3>Veranstaltungen Termine<\/h3>\n<p>der &#8222;Ka-Li 50plus &#8211; Gruppen&#8220; siehe im links nebenstehenden Kalender.<\/p>\n\t<div class=\"em em-location-map-container\"  style='position:relative; width:98%; height: 300px;'>\r\n\t\t<div class='em-locations-map' id='em-locations-map-474367015' style=\"width:100%; height:100%\">\r\n\t\t\t<div class=\"em-loading-maps\">\r\n\t\t\t\t<span>Lade Karte ...<\/span>\r\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" style=\"margin: auto; background: none; display: block; shape-rendering: auto;\" width=\"200px\" height=\"200px\" viewBox=\"0 0 100 100\" preserveAspectRatio=\"xMidYMid\">\r\n\t\t\t\t\t<rect x=\"19.5\" y=\"26\" width=\"11\" height=\"48\" fill=\"#85a2b6\">\r\n\t\t\t\t\t\t<animate attributeName=\"y\" repeatCount=\"indefinite\" dur=\"1s\" calcMode=\"spline\" keyTimes=\"0;0.5;1\" values=\"2;26;26\" keySplines=\"0 0.5 0.5 1;0 0.5 0.5 1\" begin=\"-0.2s\"><\/animate>\r\n\t\t\t\t\t\t<animate attributeName=\"height\" repeatCount=\"indefinite\" dur=\"1s\" calcMode=\"spline\" keyTimes=\"0;0.5;1\" values=\"96;48;48\" keySplines=\"0 0.5 0.5 1;0 0.5 0.5 1\" begin=\"-0.2s\"><\/animate>\r\n\t\t\t\t\t<\/rect>\r\n\t\t\t\t\t<rect x=\"44.5\" y=\"26\" width=\"11\" height=\"48\" fill=\"#bbcedd\">\r\n\t\t\t\t\t\t<animate attributeName=\"y\" repeatCount=\"indefinite\" dur=\"1s\" calcMode=\"spline\" keyTimes=\"0;0.5;1\" values=\"8;26;26\" keySplines=\"0 0.5 0.5 1;0 0.5 0.5 1\" begin=\"-0.1s\"><\/animate>\r\n\t\t\t\t\t\t<animate attributeName=\"height\" repeatCount=\"indefinite\" dur=\"1s\" calcMode=\"spline\" keyTimes=\"0;0.5;1\" values=\"84;48;48\" keySplines=\"0 0.5 0.5 1;0 0.5 0.5 1\" begin=\"-0.1s\"><\/animate>\r\n\t\t\t\t\t<\/rect>\r\n\t\t\t\t\t<rect x=\"69.5\" y=\"26\" width=\"11\" height=\"48\" fill=\"#dce4eb\">\r\n\t\t\t\t\t\t<animate attributeName=\"y\" repeatCount=\"indefinite\" dur=\"1s\" calcMode=\"spline\" keyTimes=\"0;0.5;1\" values=\"8;26;26\" keySplines=\"0 0.5 0.5 1;0 0.5 0.5 1\"><\/animate>\r\n\t\t\t\t\t\t<animate attributeName=\"height\" repeatCount=\"indefinite\" dur=\"1s\" calcMode=\"spline\" keyTimes=\"0;0.5;1\" values=\"84;48;48\" keySplines=\"0 0.5 0.5 1;0 0.5 0.5 1\"><\/animate>\r\n\t\t\t\t\t<\/rect>\r\n\t\t\t\t<\/svg>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t<div class='em-locations-map-coords' id='em-locations-map-coords-474367015' style=\"display:none; visibility:hidden;\">{&quot;ajax&quot;:true,&quot;format&quot;:&quot;&quot;,&quot;em_ajax&quot;:true,&quot;query&quot;:&quot;GlobalMapData&quot;,&quot;width&quot;:&quot;98%&quot;,&quot;height&quot;:&quot;300px&quot;,&quot;id&quot;:474367015}<\/div>\r\n\t\t\t<\/div>\r\n\t\n<h6>Unsere Gruppenadressen in 47475 Kamp-Lintfort:<\/h6>\n<ul>\n<li>Bonhoeffer-Haus \/ evg. Kirche Geisbruch, Geisbruchstr. 20<\/li>\n<li><span style=\"font-size: 100%;\">K.O.T. der Kirchengemeinde St. Josef, Kamp-Lintfort Gestfeld<br \/>\n<\/span><\/li>\n<li>Familienzentrum Arche, Fasanenstr. 10a<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Runde Tische Das ist die Vorgehensweise: In den folgenden Stadtteilen Geisbruch, Gestfeld und Niersenbruch haben sich Runde Tische gebildet, die die Anregungen und Ideen aus den 50plus-Konferenzen umsetzen. Interessierte B\u00fcrgerinnen und B\u00fcrger sind weiterhin zur Mitarbeit eingeladen. Alle Runden Tische treffen sich regelm\u00e4\u00dfig, haben mit ersten Aktivit\u00e4ten begonnen und arbeiten st\u00e4ndig daran, Neues anzubieten. Schulferien &hellip; <a href=\"https:\/\/unser-quartier.de\/kali50plus\/aktuell-termine\/\" class=\"more-link\" data-wpel-link=\"internal\"><span class=\"screen-reader-text\">Aktuelle Termine<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":168,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"ngg_post_thumbnail":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[40,41],"tags":[],"class_list":["post-18","post","type-post","status-publish","format-standard","hentry","category-stadtteile","category-veranstaltungen"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p4AdMt-i","jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_sharing_enabled":false,"_links":{"self":[{"href":"https:\/\/unser-quartier.de\/kali50plus\/wp-json\/wp\/v2\/posts\/18","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unser-quartier.de\/kali50plus\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/unser-quartier.de\/kali50plus\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/unser-quartier.de\/kali50plus\/wp-json\/wp\/v2\/users\/168"}],"replies":[{"embeddable":true,"href":"https:\/\/unser-quartier.de\/kali50plus\/wp-json\/wp\/v2\/comments?post=18"}],"version-history":[{"count":3,"href":"https:\/\/unser-quartier.de\/kali50plus\/wp-json\/wp\/v2\/posts\/18\/revisions"}],"predecessor-version":[{"id":29824,"href":"https:\/\/unser-quartier.de\/kali50plus\/wp-json\/wp\/v2\/posts\/18\/revisions\/29824"}],"wp:attachment":[{"href":"https:\/\/unser-quartier.de\/kali50plus\/wp-json\/wp\/v2\/media?parent=18"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/unser-quartier.de\/kali50plus\/wp-json\/wp\/v2\/categories?post=18"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/unser-quartier.de\/kali50plus\/wp-json\/wp\/v2\/tags?post=18"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}