{"id":2072,"date":"2017-06-19T10:43:20","date_gmt":"2017-06-19T08:43:20","guid":{"rendered":"https:\/\/unser-quartier.de\/zeitvorsorge\/?p=2072"},"modified":"2017-06-19T10:43:20","modified_gmt":"2017-06-19T08:43:20","slug":"video-mit-interview-vom-porzer-autofruehling","status":"publish","type":"post","link":"https:\/\/unser-quartier.de\/zeitvorsorge\/2017\/06\/video-mit-interview-vom-porzer-autofruehling\/","title":{"rendered":"Video mit Interview vom Porzer Autofr\u00fchling"},"content":{"rendered":"<p>Das Internetfernsehen zenterTV.de hatte auf dem Porzer Autofr\u00fchling am 10. Juni 2017 in Porz Mitte einen Film gedreht, in dem auch der Vorsitzende des Vereins Zeitvorsorge K\u00f6ln e.V. ein Interview gab (dar\u00fcber wurde bereits berichtet). Ab der 8. Minute ist das Interview zu sehen, aber es lohnt auch die ganzen 13 Minuten anzusehen: <a href=\"http:\/\/zentertv.de\/10.06.2017-porzer-autofruehling.html\" data-wpel-link=\"external\" target=\"_self\" rel=\"nofollow external noopener noreferrer\" title=\"Externer Link: Film \u00fcber Porzer Autofr\u00fchling von ZenterTV\" class=\"ext-link wpel-icon-right\">Film \u00fcber Porzer Autofr\u00fchling von ZenterTV<span class=\"wpel-icon wpel-image wpel-icon-6\"><\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Internetfernsehen zenterTV.de hatte auf dem Porzer Autofr\u00fchling am 10. Juni 2017 in Porz Mitte einen Film gedreht, in dem auch der Vorsitzende des Vereins Zeitvorsorge K\u00f6ln e.V. ein Interview gab (dar\u00fcber wurde bereits berichtet). Ab der 8. Minute ist das Interview zu sehen, aber es lohnt auch die ganzen 13 Minuten anzusehen: Film \u00fcber&hellip; <a class=\"continue\" href=\"https:\/\/unser-quartier.de\/zeitvorsorge\/2017\/06\/video-mit-interview-vom-porzer-autofruehling\/\" data-wpel-link=\"internal\"> \u00bb weiterlesen: <span> Video mit Interview vom Porzer Autofr\u00fchling<\/span><\/a><\/p>\n","protected":false},"author":520,"featured_media":2073,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"generate_page_header":"","footnotes":""},"categories":[70,72,69],"tags":[],"class_list":["post-2072","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachricht","category-oeffentlichkeitsarbeit","category-wirueberuns"],"_links":{"self":[{"href":"https:\/\/unser-quartier.de\/zeitvorsorge\/wp-json\/wp\/v2\/posts\/2072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unser-quartier.de\/zeitvorsorge\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/unser-quartier.de\/zeitvorsorge\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/unser-quartier.de\/zeitvorsorge\/wp-json\/wp\/v2\/users\/520"}],"replies":[{"embeddable":true,"href":"https:\/\/unser-quartier.de\/zeitvorsorge\/wp-json\/wp\/v2\/comments?post=2072"}],"version-history":[{"count":0,"href":"https:\/\/unser-quartier.de\/zeitvorsorge\/wp-json\/wp\/v2\/posts\/2072\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/unser-quartier.de\/zeitvorsorge\/wp-json\/wp\/v2\/media\/2073"}],"wp:attachment":[{"href":"https:\/\/unser-quartier.de\/zeitvorsorge\/wp-json\/wp\/v2\/media?parent=2072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/unser-quartier.de\/zeitvorsorge\/wp-json\/wp\/v2\/categories?post=2072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/unser-quartier.de\/zeitvorsorge\/wp-json\/wp\/v2\/tags?post=2072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}